{"id":8122,"date":"2017-12-14T18:42:28","date_gmt":"2017-12-14T18:42:28","guid":{"rendered":"http:\/\/www.viralsalud.com\/?p=8122"},"modified":"2017-12-14T18:44:34","modified_gmt":"2017-12-14T18:44:34","slug":"la-mujer-se-opero-mas-50-veces-parecerse-angelina-jolie-confiesa-lo-ha-conseguido-realmente","status":"publish","type":"post","link":"https:\/\/www.viralsalud.com\/web\/la-mujer-se-opero-mas-50-veces-parecerse-angelina-jolie-confiesa-lo-ha-conseguido-realmente\/","title":{"rendered":"La mujer que se \u2018oper\u00f3\u2019 m\u00e1s de 50 veces para parecerse a Angelina Jolie confiesa c\u00f3mo lo ha conseguido realmente"},"content":{"rendered":"<p>Hace tan solo unos d\u00edas, Sahar Taabar, una joven iran\u00ed aseguraba\u00a0<strong>haberse operado hasta en 50 ocasiones para parecerse a Angelina Jolie<\/strong>\u00a0tanto como fuese posible.<!--more--><\/p>\n<h5>La joven que se \u2018oper\u00f3\u2019 para parecerse a Angelina Jolie cuenta la verdad<\/h5>\n<p>Pero no se hizo famosa precisamente por eso, sino por el resultado de su rostro.<\/p>\n<p>con unos rasgos que se parec\u00edan m\u00e1s a los de la\u00a0<strong>Novia Cad\u00e1ver<\/strong>\u00a0que a los de la famosa actriz.<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BWeiKjkBH7A\/embed\/captioned\/?cr=1&amp;v=7&amp;wp=658#%7B%22ci%22%3A0%2C%22os%22%3A32900.995%7D\" width=\"300\" height=\"850\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Sin embargo, ya en ese momento, hubo quienes apreciaron los\u00a0<strong>cambios f\u00edsicos que experimentaba de una foto a otra<\/strong>, y aseguraban que solo se trataba de maquillaje.<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-1\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/Bcfxld5hsh9\/embed\/?cr=1&amp;v=7&amp;wp=658#%7B%22ci%22%3A1%2C%22os%22%3A32904.995%7D\" width=\"300\" height=\"756\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-1\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Poco m\u00e1s de una semana despu\u00e9s todo se ha aclarado. Cuando ya todo el mundo hab\u00eda asimilado la historia de la joven, la propia Sahar ha confesado en una entrevista con el medio ruso Sputnik que\u00a0<strong>ha enga\u00f1ado a la prensa por completo<\/strong>.<\/p>\n<p>El resultado era absolutamente nefasto, pero en su defensa tenemos que decir que el resultado de las im\u00e1genes era bastante bueno.<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-2\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BcKMR2eBy5L\/embed\/?cr=1&amp;v=7&amp;wp=658#%7B%22ci%22%3A2%2C%22os%22%3A32908.995%7D\" width=\"300\" height=\"756\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-2\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>\u201cAhora veo que puedo tener algo en com\u00fan con Angelina Jolie, pero es para divertirme. Parecerme a alguien no es mi objetivo\u201d, ha asegurado tras haberlo confirmado varias veces. Seg\u00fan ha contado,\u00a0<strong>sus conocidas \u2018operaciones\u2019 son simplemente una mezcla de Photoshop y maquillaje<\/strong>.<\/p>\n<p>Sin embargo, fue debido al\u00a0<strong>acoso que empez\u00f3 a recibir en las redes sociales<\/strong>\u00a0por lo que decidi\u00f3 privatizar su cuenta para evitar que nadie m\u00e1s tuviera acceso a sus im\u00e1genes.<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-3\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BcKMWgph773\/embed\/?cr=1&amp;v=7&amp;wp=658#%7B%22ci%22%3A3%2C%22os%22%3A39443.995%7D\" width=\"300\" height=\"756\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-3\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Pero parece que esto no va a ser posible y que va a pagar un alto precio por lo que ha hecho. Tras su decisi\u00f3n de contar toda la verdad sobre su imagen,\u00a0<strong>numerosos seguidores han publicado sus im\u00e1genes en internet<\/strong>. A\u00fan as\u00ed ella asegura: \u201cMis fans saben que esta no es mi cara real\u201d.<\/p>\n<p><iframe loading=\"lazy\" id=\"instagram-embed-4\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BcKMBMahH_j\/embed\/captioned\/?cr=1&amp;v=7&amp;wp=658#%7B%22ci%22%3A4%2C%22os%22%3A39461.995%7D\" width=\"300\" height=\"850\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-4\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>No sabemos si ha sido casualidad o intenci\u00f3n, pero si su objetivo era hacerse conocida y divertirse en las redes socales, est\u00e1 claro que lo ha conseguido.<\/p>\n<h6>Imagen de portada:\u00a0@sahar.tabar2017<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Hace tan solo unos d\u00edas, Sahar Taabar, una joven iran\u00ed aseguraba\u00a0haberse operado hasta en 50 ocasiones para parecerse a Angelina Jolie\u00a0tanto como fuese posible.<\/p>\n","protected":false},"author":1,"featured_media":8123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[59],"class_list":["post-8122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-mujer"],"jetpack_featured_media_url":"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2017\/12\/la-mujer-que-se-opero-mas-de-50-veces-para-parecerse-a-angelina-jolie-confiesa-como-lo-ha-conseguido-realmente.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/8122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/comments?post=8122"}],"version-history":[{"count":0,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/8122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media\/8123"}],"wp:attachment":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media?parent=8122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/categories?post=8122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/tags?post=8122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}