{"id":15124,"date":"2026-01-11T03:29:31","date_gmt":"2026-01-11T03:29:31","guid":{"rendered":"https:\/\/www.viralsalud.com\/web\/?p=15124"},"modified":"2026-01-11T03:38:23","modified_gmt":"2026-01-11T03:38:23","slug":"el-cantante-yeison-jimenez","status":"publish","type":"post","link":"https:\/\/www.viralsalud.com\/web\/el-cantante-yeison-jimenez\/","title":{"rendered":"El cantante colombiano Yeison Jim\u00e9nez fallece en accidente a\u00e9reo"},"content":{"rendered":"<p>Bogot\u00e1.- El cantante colombiano Yeison Jim\u00e9nez, uno de los principales exponentes de la m\u00fasica popular del pa\u00eds, muri\u00f3 este s\u00e1bado al accidentarse la avioneta en la que viajaba en una zona rural del departamento de Boyac\u00e1 (centro), informaron las autoridades.<\/p>\n<p><!--more--><\/p>\n<p>\u00abLa Aeron\u00e1utica Civil lamenta profundamente esta tragedia y expresa sus m\u00e1s sinceras condolencias a los familiares, amigos y seguidores del se\u00f1or Yeison Jim\u00e9nez, as\u00ed como a las familias de los dem\u00e1s ocupantes y la tripulaci\u00f3n\u00bb, se\u00f1al\u00f3 la entidad en un comunicado.<\/p>\n<p>Ese organismo confirm\u00f3 en un comunicado que el artista era una de las seis personas que estaban a bordo de la avioneta accidentada entre las localidades de Paipa y Duitama cuando volaba con destino a Medell\u00edn y que qued\u00f3 calcinada.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15125\" src=\"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma.jpg\" alt=\"\" width=\"810\" height=\"496\" srcset=\"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma.jpg 810w, https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma-300x184.jpg 300w, https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma-768x470.jpg 768w, https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma-686x420.jpg 686w, https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma-640x392.jpg 640w, https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma-681x417.jpg 681w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p>Jim\u00e9nez, de 34 a\u00f1os, nacido en Manzanares, en el departamento de Caldas, en el centro del pa\u00eds, fue uno de los artistas m\u00e1s influyentes de la m\u00fasica regional colombiana en la \u00faltima d\u00e9cada y figura clave en la expansi\u00f3n del g\u00e9nero popular m\u00e1s all\u00e1 de los circuitos tradicionales.<\/p>\n<p>Seg\u00fan la Gobernaci\u00f3n departamental de Boyac\u00e1, adem\u00e1s del artista, en el siniestro perdieron la vida el piloto, capit\u00e1n Hernando Torres; los pasajeros Juan Manuel Rodr\u00edguez, \u00d3scar Mar\u00edn (asistente de Jim\u00e9nez), J\u00e9fferson Osorio (representante del cantante) y Weisman Mora.<\/p>\n<p>\u00abEl Gobierno de Boyac\u00e1 (&#8230;) lamenta profundamente este hecho y se solidariza con las familias, seres queridos y seguidores en estos dif\u00edciles momentos\u00bb, se\u00f1al\u00f3 el comunicado, que agreg\u00f3 que fue decretado un duelo departamental.<\/p>\n<p>El presidente colombiano, Gustavo Petro, lament\u00f3 el accidente, del que asegur\u00f3 que no hubo sobrevivientes: \u00abLamentablemente han muerto seis personas en un avi\u00f3n que al parecer se incendi\u00f3 en vuelo, en las cercan\u00edas de Paipa\u00bb, expres\u00f3 el mandatario en X.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/YLY4UWH22ZDHXJC75GXQ6ANSRM.jpg?auth=2cfcea785f159a19c6977976b34e0fcaf299f22bb55b1e6e8bac87ff779d62b9&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" alt=\"Las redes sociales de figuras\" width=\"519\" height=\"292\" \/><\/p>\n<p>Jim\u00e9nez se hab\u00eda presentado el viernes en la localidad de M\u00e1laga, en el departamento de Santander, y ten\u00eda prevista una presentaci\u00f3n la noche de este s\u00e1bado en el municipio de Marinilla, en el departamento de Antioquia, cercano a Medell\u00edn, como parte de su agenda art\u00edstica.<\/p>\n<p>Canciones como &#8216;Aventurero&#8217;, &#8216;Vete&#8217; y &#8216;Mi venganza&#8217; lo consolidaron como uno de los int\u00e9rpretes con mayor convocatoria en Colombia.<\/p>\n<p>En 2021 fue reconocido como artista revelaci\u00f3n latino por la revista Billboard y en los \u00faltimos a\u00f1os logr\u00f3 llenar grandes escenarios del pa\u00eds, entre ellos el Movistar Arena de Bogot\u00e1, un hito para un g\u00e9nero hist\u00f3ricamente asociado a espacios m\u00e1s peque\u00f1os.<\/p>\n<p>Pipe Bueno, amigo cercano de Jim\u00e9nez y con el que colabor\u00f3 en la recordada\u00a0<i>Tengo Ganas<\/i>, manifest\u00f3: \u201cTodav\u00eda no logro procesar esta noticia\u2026 Pero decido quedarme con los recuerdos y la gratitud.\u00a0Con todo lo que viv\u00ed junto a un amigo, pero tambi\u00e9n junto al colega, al compa\u00f1ero de tarimas, de canciones y de sue\u00f1os. Yeison dej\u00f3 huella en mi vida y en la de muchos.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F863654276441781%2F&amp;show_text=false&amp;width=476&amp;t=0\" width=\"476\" height=\"476\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">\u00a0No solo por su talento, sino por su forma de ser y habitar el mundo\u00a0(&#8230;) Hoy el g\u00e9nero popular Colombiano est\u00e1 de luto. Perdimos a alguien que le dio un sentido enorme a esta industria. Todo mi amor y solidaridad para su familia, amigos y seguidores. Paz en tu camino, hermano.\u201d<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El exfutbolista Ren\u00e9 Higuita tambi\u00e9n lament\u00f3 la p\u00e9rdida y public\u00f3 en su cuenta:\u00a0<b>\u201cQu\u00e9 dolor tan grande la p\u00e9rdida de nuestro amigo, hermano, hincha de nuestro atl\u00e9tico nacional. Descansa en paz.\u201d<\/b><\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">El artista Carlos Vives expres\u00f3 su pesar previo a su concierto en la Feria de Manizales, donde el fallecido cantante se present\u00f3 d\u00edas atr\u00e1s. En su cuenta oficial, comparti\u00f3:\u00a0\u201cEstoy cerca a la tierra de Yeison Jim\u00e9nez. No es f\u00e1cil salir a cantar hoy en la feria de Manizales con esta tristeza en el coraz\u00f3n. Lo siento mucho, mucha fuerza para su familia\u201d, acompa\u00f1ado de una imagen en blanco y negro de Jim\u00e9nez sobre el escenario.<\/p>\n<p class=\"paragraph\" data-mrf-recirculation=\"Links inline\">En Instagram, el actor Juan Pablo Raba que entrevist\u00f3 al cantante en su p\u00f3dcast\u00a0<i>Los Hombres S\u00ed Lloran<\/i>\u00a0public\u00f3 una fotograf\u00eda abrazando a Jim\u00e9nez, junto al mensaje:\u00a0\u201cMe quedo con tu generosidad, con tu sonrisa, con tu entusiasmo, con tus ganas, tu fuerza y tu honestidad. Me quedo con este abrazo. Descansa en paz\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h3><em><strong>Ver video:<\/strong><\/em><\/h3>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F1524381632193456%2F&amp;show_text=false&amp;width=476&amp;t=0\" width=\"476\" height=\"476\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F1547434413179515%2F&amp;show_text=false&amp;width=476&amp;t=0\" width=\"476\" height=\"476\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1.- El cantante colombiano Yeison Jim\u00e9nez, uno de los principales exponentes de la m\u00fasica popular del pa\u00eds, muri\u00f3 este s\u00e1bado al accidentarse la avioneta en la que viajaba en una zona rural del departamento de Boyac\u00e1 (centro), informaron las autoridades.<\/p>\n","protected":false},"author":1,"featured_media":15125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-15124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"jetpack_featured_media_url":"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2026\/01\/yeiamomaocma.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/15124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/comments?post=15124"}],"version-history":[{"count":0,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/15124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media\/15125"}],"wp:attachment":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media?parent=15124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/categories?post=15124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/tags?post=15124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}