{"id":13135,"date":"2023-08-11T15:26:12","date_gmt":"2023-08-11T15:26:12","guid":{"rendered":"https:\/\/www.viralsalud.com\/?p=13135"},"modified":"2023-08-11T15:26:12","modified_gmt":"2023-08-11T15:26:12","slug":"doble-de-luis-miguel-admite-que-ha-sustituido-al-cantante-en-algunos-conciertos","status":"publish","type":"post","link":"https:\/\/www.viralsalud.com\/web\/doble-de-luis-miguel-admite-que-ha-sustituido-al-cantante-en-algunos-conciertos\/","title":{"rendered":"Doble de Luis Miguel admite que ha sustituido al cantante en algunos conciertos"},"content":{"rendered":"<p>El cantante Luis Miguel ha regresado a los escenarios tras cuatro a\u00f1os de ausencia, el cantante ha generado bastante pol\u00e9mica por su actuaci\u00f3n y nuevo look.<\/p>\n<p><!--more--><\/p>\n<p>Muchos de los espectadores de sus shows han asegurado que el cantante se ve de una forma completamente diferente, tanto por su delgadez extrema como por su forma de interpretar sus canciones y moverse en el escenario, asegurando que es un doble del artista.<\/p>\n<p>Y la realidad hay que decirla, el cantante se ve muy diferente a como luc\u00eda en el a\u00f1o 2019, en medio del esc\u00e1ndalo generado por su apariencia el d\u00eda de hoy a salido a la luz p\u00fablica una entrevista en la que uno de sus imitadores asegur\u00f3 que reemplaz\u00f3 al cantante en m\u00e1s de una ocasi\u00f3n.<\/p>\n<p>Estas declaraciones fueron dadas en el programa El Diario de Mariana, donde el hombre admiti\u00f3 haberlo reemplazado en uno de sus conciertos en Argentina, el doble se trata de Andr\u00e9s Urrustarazu, mejor conocido en los medios como Andr\u00e9s Rey.<\/p>\n<p>Andr\u00e9s Rey admiti\u00f3 que el 13 de noviembre del a\u00f1o 2010 que en un concierto en Argentina 40 minutos despu\u00e9s de arrancar, el artista se quej\u00f3 de los problemas t\u00e9cnicos con el sonido y abandon\u00f3 el escenario, y que para no quedarle mal al p\u00fablico, \u00e9l se vio obligado a tomar su lugar a fin de concluir la lista de canciones.<\/p>\n<p>El hombre tambi\u00e9n confes\u00f3: \u201cHay un contrato de confidencialidad y mucho que no puedo contar, pero en San Luis hubo un episodio, y en otros lugares tambi\u00e9n, se fueron armando distintos tipos de giras y, cuando hab\u00eda fallas de sonido o no estaba lo pactado, el artista suspend\u00eda los shows\u201d, cont\u00f3 el imitador.<\/p>\n<p>El hombre recalc\u00f3 que aquella noche nadie sospech\u00f3 nada, todos quedaron emocionados creyendo haber visto al astro de la m\u00fasica d\u00e1ndolo en el escenario y no fue as\u00ed. \u201cHace 20 a\u00f1os que me dedico a esto\u201d, a\u00f1adi\u00f3 a modo de confirmar que no es la primera vez que esto sucede.<\/p>\n<p>Que te parecen las declaraciones de este doble del artista, si el hombre est\u00e1 diciendo la verdad definitivamente el artista estar\u00eda perdiendo credibilidad.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Ver video:<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/oPiWp-PL5jE\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Luis Miguel ha regresado a los escenarios tras cuatro a\u00f1os de ausencia, el cantante ha generado bastante pol\u00e9mica por su actuaci\u00f3n y nuevo look.<\/p>\n","protected":false},"author":1,"featured_media":13136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[963],"class_list":["post-13135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-luis-miguel"],"jetpack_featured_media_url":"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2023\/08\/efaldusiamsoamdoamrai.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/13135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/comments?post=13135"}],"version-history":[{"count":0,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/13135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media\/13136"}],"wp:attachment":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media?parent=13135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/categories?post=13135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/tags?post=13135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}