{"id":1165,"date":"2015-05-20T07:45:17","date_gmt":"2015-05-20T07:45:17","guid":{"rendered":"http:\/\/www.genoviral.com\/?p=1165"},"modified":"2015-05-20T07:45:17","modified_gmt":"2015-05-20T07:45:17","slug":"conoce-a-lauren-la-nina-que-no-puede-evitar-saludar-a-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/www.viralsalud.com\/web\/conoce-a-lauren-la-nina-que-no-puede-evitar-saludar-a-todo-el-mundo\/","title":{"rendered":"Conoce A Lauren, La Ni\u00f1a Que No Puede Evitar Saludar A Todo El Mundo"},"content":{"rendered":"<div>\u00a0Pero qu\u00e9 suceder\u00eda si eso no se puede controlar? \u00bfQu\u00e9 pasar\u00eda si el ni\u00f1o\/a no pudiera evitarlo y saludara con una gran sonrisa a todas las personas que pasan?<\/div>\n<p>Con su hija Lauren, Katherine y Paul tienen que lidiar con esta situaci\u00f3n todos los d\u00edas. Lauren es una ni\u00f1a extremadamente simp\u00e1tica de tan solo 3 a\u00f1os, que padece el s\u00edndrome de Williams. <!--more-->El s\u00edndrome de Williams afecta a 1 de cada 7500 reci\u00e9n nacidos, es una enfermedad muy rara cuya caracter\u00edstica m\u00e1s notable es el comportamiento. Lauren no puede evitar interactuar con todas las personas que se cruzan por su camino, tiene una personalidad s\u00faper amigable, desinhibida y entusiasta.<\/p>\n<p>A sus cortos 3 a\u00f1os de vida, sus padres pueden cuidarla y guiarla f\u00e1cilmente a trav\u00e9s de su enfermedad, es por eso que en vez de temer por su seguridad, de alguna manera disfrutan de su condici\u00f3n, ya que Lauren llena sus vidas de felicidad y despu\u00e9s de ver estas fotos entender\u00e1s por qu\u00e9.<\/p>\n<h2>Cuando la peque\u00f1a Lauren naci\u00f3, sus padres primerizos Katherine y Paul estaban muy felices. Desde el momento que la conocieron, sab\u00edan que hab\u00eda algo especial en ella.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19734 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-1.jpg\" alt=\"Lauren-historia-1\" width=\"600\" height=\"780\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-1.jpg\" \/><\/p>\n<h2>Pero Katherine y Paul r\u00e1pidamente se dieron cuenta de que no eran solo sus enormes y hermosos ojos celestes lo que la hac\u00edan tan especial\u2026 A Katherine le hicieron una ces\u00e1rea a las 36 semanas, Lauren ten\u00eda muy poco peso y la tuvieron que llevar a una unidad especial donde pasar\u00eda los siguientes 22 d\u00edas.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19735 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-2.jpg\" alt=\"Lauren-historia-2\" width=\"600\" height=\"800\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-2.jpg\" \/><\/p>\n<h2>Cuatro meses despu\u00e9s, los doctores descubrieron que la peque\u00f1a padec\u00eda el s\u00edndrome de Williams. Una enfermedad muy rara que afecta el coraz\u00f3n, y causa retraso en el desarrollo en otras cosas.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19736 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-3.jpg\" alt=\"Lauren-historia-3\" width=\"600\" height=\"901\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-3.jpg\" \/><\/p>\n<h2>Pero tambi\u00e9n hace que Lauren sea muy amigable y simp\u00e1tica con todas las personas que ve.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19737 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-4.jpg\" alt=\"Lauren-historia-4\" width=\"600\" height=\"822\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-4.jpg\" \/><\/p>\n<h2>Lauren sabe pocas palabras, pero el \u2018Hola\u2019 siempre est\u00e1 presente. A causa de su desorden, ella no puede evitar saludar a todos los extra\u00f1os que pasan, y no le teme a nadie.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19738 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-5.jpg\" alt=\"Lauren-historia-5\" width=\"600\" height=\"399\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-5.jpg\" \/><\/p>\n<h2>Ir al supermercado puede tomar horas\u2026 ya que Lauren quiere detenerse a saludar a todos con una gran sonrisa. La mayor\u00eda de las personas tambi\u00e9n la saludan y dicen que luce como una peque\u00f1a mu\u00f1eca.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"lazy alignnone size-full wp-image-19740 data-lazy-ready\" src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-7.jpg\" alt=\"Lauren-historia-7\" width=\"600\" height=\"901\" data-lazy-type=\"image\" data-lazy-src=\"http:\/\/cdn.viralismo.com\/wp-content\/uploads\/2015\/05\/Lauren-historia-7.jpg\" \/><\/p>\n<h2>Aunque el futuro de la salud de Lauren es incierto, sus padres tratan de disfrutar cada momento con su dulce hija, que no hace m\u00e1s que irradiar felicidad y contagiar su alegr\u00eda.<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Pero qu\u00e9 suceder\u00eda si eso no se puede controlar? \u00bfQu\u00e9 pasar\u00eda si el ni\u00f1o\/a no pudiera evitarlo y saludara con una gran sonrisa a todas las personas que pasan? Con su hija Lauren, Katherine y Paul tienen que lidiar con esta situaci\u00f3n todos los d\u00edas. Lauren es una ni\u00f1a extremadamente simp\u00e1tica de tan solo 3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,1],"tags":[],"class_list":["post-1165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sorprendente","category-uncategorized"],"jetpack_featured_media_url":"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2015\/05\/Lauren-historia-9-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":0,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media\/1166"}],"wp:attachment":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}