{"id":11355,"date":"2022-04-04T22:05:52","date_gmt":"2022-04-04T22:05:52","guid":{"rendered":"https:\/\/www.viralsalud.com\/?p=11355"},"modified":"2022-04-04T22:05:52","modified_gmt":"2022-04-04T22:05:52","slug":"como-lidiar-efectivamente-con-trombosis-venosa-profunda","status":"publish","type":"post","link":"https:\/\/www.viralsalud.com\/web\/como-lidiar-efectivamente-con-trombosis-venosa-profunda\/","title":{"rendered":"C\u00f3mo lidiar efectivamente con trombosis venosa profunda"},"content":{"rendered":"<p>Debido a que todos tenemos sangre circulando por nuestras venas, todos corremos el riesgo de sufrir una trombosis venosa profunda (TVP), una afecci\u00f3n en la que se forman co\u00e1gulos de sangre en las venas del interior del cuerpo.<\/p>\n<p><!--more--><\/p>\n<p>Los m\u00e9dicos tratan la trombosis venosa profunda (TVP) con medicamentos y otros dispositivos y terapias.<\/p>\n<p>Los principales objetivos del tratamiento de la TVP son: Detener el co\u00e1gulo de sangre antes de que crezca Evitar que el co\u00e1gulo se rompa y pase a los pulmones Reducir el riesgo de que se forme otro co\u00e1gulo de sangre.<\/p>\n<p>Se pueden formar co\u00e1gulos de sangre en las piernas, un problema de salud conocido como trombosis venosa profunda.<\/p>\n<p>Una enfermedad que puede complicarse si no se trata ya que el co\u00e1gulo que se forma puede viajar por el torrente sangu\u00edneo hasta los pulmones y provocar un tromboembolismo pulmonar.<\/p>\n<p>Sigue los consejos de la Dra. Ana Cristina Montenegro, internista vascular aqu\u00ed:<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/oRBdH3yRE_0\" width=\"100%\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a que todos tenemos sangre circulando por nuestras venas, todos corremos el riesgo de sufrir una trombosis venosa profunda (TVP), una afecci\u00f3n en la que se forman co\u00e1gulos de sangre en las venas del interior del cuerpo.<\/p>\n","protected":false},"author":1,"featured_media":11356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[863],"tags":[],"class_list":["post-11355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"jetpack_featured_media_url":"https:\/\/www.viralsalud.com\/web\/wp-content\/uploads\/2022\/04\/westaenfwemrmnakmnaieasi.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/11355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/comments?post=11355"}],"version-history":[{"count":0,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/posts\/11355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media\/11356"}],"wp:attachment":[{"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/media?parent=11355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/categories?post=11355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viralsalud.com\/web\/wp-json\/wp\/v2\/tags?post=11355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}